{"id":10,"count":187,"description":"","link":"https:\/\/wagayoga.com\/blog\/category\/healthy-living\/healthy-activities\/","name":"Healthy Activities","slug":"healthy-activities","taxonomy":"category","parent":8,"meta":[],"_links":{"self":[{"href":"https:\/\/wagayoga.com\/blog\/wp-json\/wp\/v2\/categories\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wagayoga.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/wagayoga.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/wagayoga.com\/blog\/wp-json\/wp\/v2\/categories\/8"}],"wp:post_type":[{"href":"https:\/\/wagayoga.com\/blog\/wp-json\/wp\/v2\/posts?categories=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}